{"id":4737,"date":"2024-04-08T11:07:09","date_gmt":"2024-04-08T11:07:09","guid":{"rendered":"https:\/\/fajarindonesianews.id\/?p=4737"},"modified":"2024-10-01T03:33:27","modified_gmt":"2024-10-01T03:33:27","slug":"kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa","status":"publish","type":"post","link":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/","title":{"rendered":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Gowa | <span style=\"color: #000000;\"><em>Fajarindonesianews.id &#8211; <\/em><\/span><\/strong><\/span>Kapolres Gowa AKBP Reonald T.S Simanjuntak, S.H., S.I.K., M.M., M.I.K, bersama Wakapolres Gowa KOMPOL Gani, S.H,M.H, memimpin acara penyerahan Zakat Fitrah Personel dan Istri serta ASN Polres Gowa di ruang kerja Kapolres, Senin (08\/04\/2024).<\/p>\n<p>Dalam kesempatan tersebut, Kapolres Gowa didampingi Wakapolres menyerahkan Zakat Fitrah dari personel Polres Gowa senilai Rp 15.000.000,- kepada BAZNAS Kabupaten Gowa. Selain itu, bantuan juga disalurkan kepada penerima manfaat seperti Pengurus Panti Asuhan, Purnawirawan Polri, pensiunan PNS Polri, Fakir Miskin, dan Perwakilan Warakawuri.<\/p>\n<p>Dalam pernyataannya, Kapolres Gowa menyampaikan harapannya bahwa zakat yang disalurkan dapat memberikan manfaat bagi yang membutuhkan. &#8220;Hari ini secara simbolis kami serahkan zakat fitrah untuk seluruh personel dan istri serta ASN Polres Gowa, semoga bermanfaat nantinya bagi yang membutuhkan,&#8221; ucap Kapolres.<\/p>\n<p>Selain itu, zakat fitrah dari personel Polres Gowa juga disalurkan kepada Pondok Pesantren Yatama Mandiri sebesar Rp 30.000.000,- sebagai bentuk dukungan kepada lembaga yang berperan dalam mendidik generasi masa depan.<\/p>\n<p>Kegiatan ini menunjukkan komitmen Polres Gowa dalam berbagi dan peduli terhadap masyarakat, serta menjalankan kewajiban agama dengan penuh kesadaran.<\/p>\n<p>Humas Polres Gowa<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gowa | Fajarindonesianews.id &#8211; Kapolres Gowa AKBP Reonald T.S Simanjuntak, S.H., S.I.K., M.M., M.I.K, bersama Wakapolres Gowa KOMPOL Gani, S.H,M.H, memimpin acara penyerahan Zakat Fitrah Personel dan Istri serta ASN Polres Gowa di ruang kerja Kapolres, Senin (08\/04\/2024). Dalam kesempatan tersebut, Kapolres Gowa didampingi Wakapolres menyerahkan Zakat Fitrah dari personel Polres Gowa senilai Rp 15.000.000,-<\/p>\n","protected":false},"author":2,"featured_media":4739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,6,11,10],"tags":[149],"class_list":["post-4737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hukum","category-nasional","category-pariwisata","category-seni-budaya","tag-polres-gowa-polda-sulsel-mabes-polri"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.5 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa - Fajar Indonesia News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa\" \/>\n<meta property=\"og:description\" content=\"Gowa | Fajarindonesianews.id &#8211; Kapolres Gowa AKBP Reonald T.S Simanjuntak, S.H., S.I.K., M.M., M.I.K, bersama Wakapolres Gowa KOMPOL Gani, S.H,M.H, memimpin acara penyerahan Zakat Fitrah Personel dan Istri serta ASN Polres Gowa di ruang kerja Kapolres, Senin (08\/04\/2024). Dalam kesempatan tersebut, Kapolres Gowa didampingi Wakapolres menyerahkan Zakat Fitrah dari personel Polres Gowa senilai Rp 15.000.000,-\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fajar Indonesia News\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-08T11:07:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T03:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ikhsan Mapparenta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ditulis oleh\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ikhsan Mapparenta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimasi waktu membaca\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 menit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/\"},\"author\":{\"name\":\"Ikhsan Mapparenta\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#\\\/schema\\\/person\\\/ab7f104c35e5f8aa1d32b8d11c605044\"},\"headline\":\"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa\",\"datePublished\":\"2024-04-08T11:07:09+00:00\",\"dateModified\":\"2024-10-01T03:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG-20240408-WA0114-scaled.jpg\",\"keywords\":[\"#polres gowa #polda sulsel #mabes polri\"],\"articleSection\":[\"Hukum\",\"Nasional\",\"Pariwisata\",\"Seni &amp; Budaya\"],\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/\",\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/\",\"name\":\"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa - Fajar Indonesia News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG-20240408-WA0114-scaled.jpg\",\"datePublished\":\"2024-04-08T11:07:09+00:00\",\"dateModified\":\"2024-10-01T03:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG-20240408-WA0114-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMG-20240408-WA0114-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/2024\\\/04\\\/08\\\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fajarindonesianews.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#website\",\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/\",\"name\":\"Fajar Indonesia News\",\"description\":\"Satu Berita Untuk Semua\",\"publisher\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fajarindonesianews.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#organization\",\"name\":\"Fajar Indonesia News\",\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png\",\"contentUrl\":\"https:\\\/\\\/fajarindonesianews.id\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png\",\"width\":1130,\"height\":331,\"caption\":\"Fajar Indonesia News\"},\"image\":{\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fajarindonesianews.id\\\/#\\\/schema\\\/person\\\/ab7f104c35e5f8aa1d32b8d11c605044\",\"name\":\"Ikhsan Mapparenta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g\",\"caption\":\"Ikhsan Mapparenta\"},\"sameAs\":[\"http:\\\/\\\/fajarindonesianews.id\"],\"url\":\"https:\\\/\\\/fajarindonesianews.id\\\/index.php\\\/author\\\/adminfajarindonesia-id\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa - Fajar Indonesia News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/","og_locale":"id_ID","og_type":"article","og_title":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa","og_description":"Gowa | Fajarindonesianews.id &#8211; Kapolres Gowa AKBP Reonald T.S Simanjuntak, S.H., S.I.K., M.M., M.I.K, bersama Wakapolres Gowa KOMPOL Gani, S.H,M.H, memimpin acara penyerahan Zakat Fitrah Personel dan Istri serta ASN Polres Gowa di ruang kerja Kapolres, Senin (08\/04\/2024). Dalam kesempatan tersebut, Kapolres Gowa didampingi Wakapolres menyerahkan Zakat Fitrah dari personel Polres Gowa senilai Rp 15.000.000,-","og_url":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/","og_site_name":"Fajar Indonesia News","article_published_time":"2024-04-08T11:07:09+00:00","article_modified_time":"2024-10-01T03:33:27+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg","type":"image\/jpeg"}],"author":"Ikhsan Mapparenta","twitter_card":"summary_large_image","twitter_misc":{"Ditulis oleh":"Ikhsan Mapparenta","Estimasi waktu membaca":"2 menit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#article","isPartOf":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/"},"author":{"name":"Ikhsan Mapparenta","@id":"https:\/\/fajarindonesianews.id\/#\/schema\/person\/ab7f104c35e5f8aa1d32b8d11c605044"},"headline":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa","datePublished":"2024-04-08T11:07:09+00:00","dateModified":"2024-10-01T03:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/fajarindonesianews.id\/#organization"},"image":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#primaryimage"},"thumbnailUrl":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg","keywords":["#polres gowa #polda sulsel #mabes polri"],"articleSection":["Hukum","Nasional","Pariwisata","Seni &amp; Budaya"],"inLanguage":"id","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/","url":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/","name":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa - Fajar Indonesia News","isPartOf":{"@id":"https:\/\/fajarindonesianews.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#primaryimage"},"image":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#primaryimage"},"thumbnailUrl":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg","datePublished":"2024-04-08T11:07:09+00:00","dateModified":"2024-10-01T03:33:27+00:00","breadcrumb":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#primaryimage","url":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg","contentUrl":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2024\/04\/IMG-20240408-WA0114-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/fajarindonesianews.id\/index.php\/2024\/04\/08\/kapolres-gowa-serahkan-zakat-fitrah-personel-kepada-baznas-kabupaten-gowa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fajarindonesianews.id\/"},{"@type":"ListItem","position":2,"name":"Kapolres Gowa Serahkan Zakat Fitrah Personel Kepada BAZNAS Kabupaten Gowa"}]},{"@type":"WebSite","@id":"https:\/\/fajarindonesianews.id\/#website","url":"https:\/\/fajarindonesianews.id\/","name":"Fajar Indonesia News","description":"Satu Berita Untuk Semua","publisher":{"@id":"https:\/\/fajarindonesianews.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fajarindonesianews.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/fajarindonesianews.id\/#organization","name":"Fajar Indonesia News","url":"https:\/\/fajarindonesianews.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/","url":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png","contentUrl":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png","width":1130,"height":331,"caption":"Fajar Indonesia News"},"image":{"@id":"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fajarindonesianews.id\/#\/schema\/person\/ab7f104c35e5f8aa1d32b8d11c605044","name":"Ikhsan Mapparenta","image":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/secure.gravatar.com\/avatar\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a0350a157af3ce603dec945930dc9013753c4a1f27d08c71fa77e5914e819678?s=96&d=mm&r=g","caption":"Ikhsan Mapparenta"},"sameAs":["http:\/\/fajarindonesianews.id"],"url":"https:\/\/fajarindonesianews.id\/index.php\/author\/adminfajarindonesia-id\/"}]}},"_links":{"self":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/posts\/4737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/comments?post=4737"}],"version-history":[{"count":4,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/posts\/4737\/revisions"}],"predecessor-version":[{"id":4743,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/posts\/4737\/revisions\/4743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/media\/4739"}],"wp:attachment":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/media?parent=4737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/categories?post=4737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/tags?post=4737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}