{"id":40,"count":1,"description":"","link":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/","name":"#BPN","slug":"bpn","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.2.1 (Yoast SEO v20.2.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#BPN Archives - Fajar Indonesia News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#BPN Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/\" \/>\n<meta property=\"og:site_name\" content=\"Fajar Indonesia News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/\",\"url\":\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/\",\"name\":\"#BPN Archives - Fajar Indonesia News\",\"isPartOf\":{\"@id\":\"https:\/\/fajarindonesianews.id\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fajarindonesianews.id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#BPN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fajarindonesianews.id\/#website\",\"url\":\"https:\/\/fajarindonesianews.id\/\",\"name\":\"Fajar Indonesia News\",\"description\":\"Satu Berita Untuk Semua\",\"publisher\":{\"@id\":\"https:\/\/fajarindonesianews.id\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fajarindonesianews.id\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fajarindonesianews.id\/#organization\",\"name\":\"Fajar Indonesia News\",\"url\":\"https:\/\/fajarindonesianews.id\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png\",\"contentUrl\":\"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png\",\"width\":1130,\"height\":331,\"caption\":\"Fajar Indonesia News\"},\"image\":{\"@id\":\"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#BPN Archives - Fajar Indonesia News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/","og_locale":"id_ID","og_type":"article","og_title":"#BPN Archives","og_url":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/","og_site_name":"Fajar Indonesia News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/","url":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/","name":"#BPN Archives - Fajar Indonesia News","isPartOf":{"@id":"https:\/\/fajarindonesianews.id\/#website"},"breadcrumb":{"@id":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/fajarindonesianews.id\/index.php\/tag\/bpn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fajarindonesianews.id\/"},{"@type":"ListItem","position":2,"name":"#BPN"}]},{"@type":"WebSite","@id":"https:\/\/fajarindonesianews.id\/#website","url":"https:\/\/fajarindonesianews.id\/","name":"Fajar Indonesia News","description":"Satu Berita Untuk Semua","publisher":{"@id":"https:\/\/fajarindonesianews.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fajarindonesianews.id\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/fajarindonesianews.id\/#organization","name":"Fajar Indonesia News","url":"https:\/\/fajarindonesianews.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/","url":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png","contentUrl":"https:\/\/fajarindonesianews.id\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_fhk7s7fhk7s7fhk7-Photoroom.png","width":1130,"height":331,"caption":"Fajar Indonesia News"},"image":{"@id":"https:\/\/fajarindonesianews.id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/tags\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fajarindonesianews.id\/index.php\/wp-json\/wp\/v2\/posts?tags=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}